{"id":18,"date":"2023-04-03T20:31:58","date_gmt":"2023-04-03T18:31:58","guid":{"rendered":"https:\/\/istitutobuenosaires.esteri.it\/?page_id=18"},"modified":"2023-05-23T08:54:24","modified_gmt":"2023-05-23T13:54:24","slug":"news","status":"publish","type":"page","link":"https:\/\/iicchicago.esteri.it\/it\/news\/","title":{"rendered":"Notizie"},"content":{"rendered":"        <div class=\"row\">\n\t\t\t<!-- Ricerca sedi post -->\n\t\t\t<div class=\"col-12 mt-4\">\n\t\t\t  <div class=\"callout callout-highlight note ricerca-esteri p-4\">\n                    <div class=\"callout-title\">\n                        <svg class=\"icon\">\n                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-search\"><\/use>\n                        <\/svg>Inserisci i parametri di ricerca                    <\/div>\n                    <form id=\"searchFormPost\" name=\"form-search-post\" class=\"form-row align-items-center\" action=\"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/pages\/18\/\" method=\"GET\"> \n                        <!-- <div class=\"form-group pt-5\"> -->\n                            <!-- <input type=\"hidden\" id=\"lang\" name=\"lang\" value=\"\"> --> <!-- <\/div> -->\n\n                        <div class=\"it-datepicker-wrapper\">\n                            <div class=\"row\">\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-init\">Dal<\/label>\n                                    <input class=\"form-control\" name=\"date-init\" id=\"date-init\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\"lang=\"en-EN\">  \n                                <\/div>\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-end\">Al<\/label>\n                                    <input class=\"form-control\" name=\"date-end\" id=\"date-end\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"form-group col-md-12 mt-3\">\n                            <label for=\"searchText\">Campo ricerca libera<\/label>\n                            <input type=\"text\" name=\"searchText\" class=\"form-control\" id=\"searchText\" value=\"\">\n                        <\/div>\n                        <div class=\"form-group col-md-4 offset-md-8 text-end\">\n                            <a href=\"https:\/\/iicchicago.esteri.it\/it\/news\/\" title=\"Form reset\" id=\"resetImput\" class=\"btn btn-outline-primary btn-xs\">Reset<\/a>\n                            <button type=\"submit\" class=\"btn btn-primary btn-xs\">Mostra risultati<\/button>\n                        <\/div>\n                    <\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n                    \n            <div class=\"row\">\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 24 Aprile 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2026\/04\/contributi-per-missioni-di-studio-e-ricerca-2026\/\" title=\"Contributi per missioni di studio e ricerca 2026\">Contributi per missioni di studio e ricerca 2026<\/a><\/h5>\n                            <p class=\"card-text\">Il Ministero degli Affari Esteri e della Cooperazione Internazionale, Direzione Generale per la Crescita e la Promozione delle Esportazioni (DGCE), tramite l\u2019Ufficio VI: promozione della cultura italiana, eroga contributi ad istanza di parte per: il finanziamento delle spese di viaggio e soggiorno di ricercatori, docenti, esperti, personalit\u00e0 della cultura e operatori culturali italiani o stranieri\u00a0residenti [&hellip;]<\/p>\n                                <a title=\"Contributi per missioni di studio e ricerca 2026\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2026\/04\/contributi-per-missioni-di-studio-e-ricerca-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 27 Marzo 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2026\/03\/listituto-italiano-di-cultura-di-chicago-e-la-renaissance-society-co-organizzeranno-una-cena-privata-con-lartista-maurizio-cattelan-in-occasione-di-renben-2026\/\" title=\"L\u2019ISTITUTO ITALIANO DI CULTURA DI CHICAGO E LA RENAISSANCE SOCIETY CO-ORGANIZZERANNO UNA CENA PRIVATA CON L\u2019ARTISTA MAURIZIO CATTELAN IN OCCASIONE DI RENBEN 2026\">L\u2019ISTITUTO ITALIANO DI CULTURA DI CHICAGO E LA RENAISSANCE SOCIETY CO-ORGANIZZERANNO UNA CENA PRIVATA CON L\u2019ARTISTA MAURIZIO CATTELAN IN OCCASIONE DI RENBEN 2026<\/a><\/h5>\n                            <p class=\"card-text\">Maurizio Cattelan concepir\u00e0 e orchestrer\u00e0 RenBen 2026, che si terr\u00e0 a Chicago mercoled\u00ec 8 aprile 2026, durante la EXPO Art Week di Chicago. L\u2019Istituto Italiano di Cultura di Chicago \u00e8 lieto di annunciare una nuova collaborazione con la Renaissance Society per co-organizzare una cena privata in onore dell\u2019artista italiano di fama internazionale Maurizio Cattelan, che [&hellip;]<\/p>\n                                <a title=\"L\u2019ISTITUTO ITALIANO DI CULTURA DI CHICAGO E LA RENAISSANCE SOCIETY CO-ORGANIZZERANNO UNA CENA PRIVATA CON L\u2019ARTISTA MAURIZIO CATTELAN IN OCCASIONE DI RENBEN 2026\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2026\/03\/listituto-italiano-di-cultura-di-chicago-e-la-renaissance-society-co-organizzeranno-una-cena-privata-con-lartista-maurizio-cattelan-in-occasione-di-renben-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 24 Febbraio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2026\/02\/avviso-pubblico-per-manifestazioni-di-interesse-per-lorganizzazione-e-la-gestione-dei-corsi-di-lingua-e-cultura-italiana-presso-listituto-italiano-di-cultura-di-chicago\/\" title=\"Avviso pubblico per manifestazioni di interesse per l\u2019organizzazione e la gestione dei corsi di lingua e cultura italiana presso l\u2019Istituto Italiano di Cultura di Chicago\">Avviso pubblico per manifestazioni di interesse per l\u2019organizzazione e la gestione dei corsi di lingua e cultura italiana presso l\u2019Istituto Italiano di Cultura di Chicago<\/a><\/h5>\n                            <p class=\"card-text\">\u00c8 stato pubblicato l\u2019avviso pubblico per l\u2019acquisizione di manifestazioni d\u2019interesse a partecipare alla procedura negoziata per l\u2019organizzazione e la gestione dei corsi di lingua e cultura italiana presso l\u2019Istituto Italiano di Cultura di Chicago per il periodo dal 19 aprile 2026 al 18 aprile 2027. Gli operatori economici autorizzati a svolgere tale attivit\u00e0 negli Stati [&hellip;]<\/p>\n                                <a title=\"Avviso pubblico per manifestazioni di interesse per l\u2019organizzazione e la gestione dei corsi di lingua e cultura italiana presso l\u2019Istituto Italiano di Cultura di Chicago\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2026\/02\/avviso-pubblico-per-manifestazioni-di-interesse-per-lorganizzazione-e-la-gestione-dei-corsi-di-lingua-e-cultura-italiana-presso-listituto-italiano-di-cultura-di-chicago\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 24 Febbraio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2026\/02\/bando-per-la-richiesta-di-contributi-e-premi-per-la-traduzione-edizione-2026\/\" title=\"Bando per la Richiesta di Contributi e Premi per la Traduzione Edizione 2026\">Bando per la Richiesta di Contributi e Premi per la Traduzione Edizione 2026<\/a><\/h5>\n                            <p class=\"card-text\">Il\u00a0Ministero degli Affari Esteri e della Cooperazione Internazionale\u00a0promuove la diffusione di opere editoriali e cinematografiche italiane all\u2019estero attraverso l\u2019erogazione di incentivi alla traduzione e al doppiaggio\/sottotitolatura che rappresentano uno strumento strategico per la promozione della lingua e della cultura italiana all\u2019estero. La Farnesina eroga due tipi di incentivi finanziari: Contributo\u00a0alla traduzione di un\u2019opera italiana all\u2019estero [&hellip;]<\/p>\n                                <a title=\"Bando per la Richiesta di Contributi e Premi per la Traduzione Edizione 2026\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2026\/02\/bando-per-la-richiesta-di-contributi-e-premi-per-la-traduzione-edizione-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 18 Novembre 2025                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/11\/studenti-al-centro-della-conversazione-us-gen-zitaly-di-francesca-beretta-e-pierluca-di-pasquale\/\" title=\"Studenti al centro della conversazione. &#8220;US: Gen Zitaly&#8221; di Francesca Beretta e Pierluca Di Pasquale\">Studenti al centro della conversazione. &#8220;US: Gen Zitaly&#8221; di Francesca Beretta e Pierluca Di Pasquale<\/a><\/h5>\n                            <p class=\"card-text\">Beretta, F., e P. Di Pasquale, creatori. US: Gen Zitaly. 2025. Articolo di Francesca Beretta Assistant Teaching Professor di Italiano e Language Coordinator | University of Kansas (KU) L\u2019idea per il cortometraggio US: Gen Zitaly (2025) \u00e8 nata davanti a un caff\u00e8 con il mio amico Pierluca di Pasquale in una panetteria di Lawrence, Kansas. [&hellip;]<\/p>\n                                <a title=\"Studenti al centro della conversazione. &#8220;US: Gen Zitaly&#8221; di Francesca Beretta e Pierluca Di Pasquale\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/11\/studenti-al-centro-della-conversazione-us-gen-zitaly-di-francesca-beretta-e-pierluca-di-pasquale\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 3 Novembre 2025                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/11\/il-salone-internazionale-del-libro-di-torino-annuncia-la-5a-edizione-di-dallitaliano-al-mondo-un-simposio-online-rivolto-a-traduttrici-e-traduttori-dallitaliano\/\" title=\"Il Salone Internazionale del Libro di Torino annuncia la 5a edizione di \u201cDall&#8217;Italiano al Mondo\u201d: un simposio online rivolto a traduttrici e traduttori dall\u2019italiano\">Il Salone Internazionale del Libro di Torino annuncia la 5a edizione di \u201cDall&#8217;Italiano al Mondo\u201d: un simposio online rivolto a traduttrici e traduttori dall\u2019italiano<\/a><\/h5>\n                            <p class=\"card-text\">Il Salone Internazionale del Libro di Torino annuncia la 5a edizione di \u201cDall&#8217;Italiano al Mondo\u201d Un simposio online rivolto a traduttrici e traduttori dall\u2019italiano Venerd\u00ec 21 novembre 2025 alle 14.30 &nbsp; &#8220;La traduzione \u00e8 il sistema circolatorio delle letterature mondiali&#8221; Susan Sontag &nbsp; Il Salone Internazionale del Libro di Torino \u00e8 lieto di annunciare la [&hellip;]<\/p>\n                                <a title=\"Il Salone Internazionale del Libro di Torino annuncia la 5a edizione di \u201cDall&#8217;Italiano al Mondo\u201d: un simposio online rivolto a traduttrici e traduttori dall\u2019italiano\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/11\/il-salone-internazionale-del-libro-di-torino-annuncia-la-5a-edizione-di-dallitaliano-al-mondo-un-simposio-online-rivolto-a-traduttrici-e-traduttori-dallitaliano\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 15 Ottobre 2025                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/10\/avviso-assunzione-collaboratore-amministrativo-iic-washington\/\" title=\"Avviso assunzione collaboratore amministrativo IIC Washington\">Avviso assunzione collaboratore amministrativo IIC Washington<\/a><\/h5>\n                            <p class=\"card-text\">Viene pubblicato l\u2019avviso di assunzione a tempo indeterminato di n. 1 (uno) Impiegato\/a a contratto da adibire al servizio di collaboratore amministrativo presso l\u2019Istituto Italiano di Cultura di Washington. Avviso assunzione collaboratore amministrativo IIC Washington &nbsp;<\/p>\n                                <a title=\"Avviso assunzione collaboratore amministrativo IIC Washington\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/10\/avviso-assunzione-collaboratore-amministrativo-iic-washington\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 26 Agosto 2025                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/08\/avviso-di-assunzione-assistente-amministrativo-presso-il-consolato-ditalia-in-detroit\/\" title=\"Avviso di Assunzione Assistente Amministrativo presso il Consolato d&#8217;Italia in Detroit\">Avviso di Assunzione Assistente Amministrativo presso il Consolato d&#8217;Italia in Detroit<\/a><\/h5>\n                            <p class=\"card-text\">Viene pubblicato l&#8217;avviso di assunzione a tempo indeterminato di n. 1 (uno) Impiegato\/a a contratto da adibire al servizio di Assistente Amministrativo\/a. Avviso di Assunzione Ass. Amm. Detroit<\/p>\n                                <a title=\"Avviso di Assunzione Assistente Amministrativo presso il Consolato d&#8217;Italia in Detroit\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/08\/avviso-di-assunzione-assistente-amministrativo-presso-il-consolato-ditalia-in-detroit\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 1 Aprile 2025                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/04\/contributi-per-missioni-di-studio-e-ricerca-2025\/\" title=\"Contributi per missioni di studio e ricerca 2025\">Contributi per missioni di studio e ricerca 2025<\/a><\/h5>\n                            <p class=\"card-text\">Il Ministero degli Affari Esteri e della Cooperazione Internazionale, DGDP, per l\u2019anno 2025 sostiene e incentiva lo svolgimento di missioni all\u2019estero e in Italia, da parte, rispettivamente, di ricercatori, docenti, esperti, personalit\u00e0 e operatori culturali italiani e stranieri invitati dalle istituzioni universitarie e culturali. Obiettivo principale del finanziamento \u00e8 favorire lo sviluppo di partenariati strategici, [&hellip;]<\/p>\n                                <a title=\"Contributi per missioni di studio e ricerca 2025\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/04\/contributi-per-missioni-di-studio-e-ricerca-2025\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 21 Marzo 2025                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/03\/affidamento-corsi-di-lingua-italiana\/\" title=\"Affidamento Corsi di Lingua Italiana\">Affidamento Corsi di Lingua Italiana<\/a><\/h5>\n                            <p class=\"card-text\">\u00c8 indetta una procedura per l\u2019affidamento diretto in concessione degli spazi e dei servizi per la gestione dei corsi di lingua italiana presso la sede dell\u2019Istituto Italiano di Cultura di Chicago, ai sensi del DM 2 novembre 2017, n.192 per l\u2019anno 2025-2026. L\u2019affidamento prevede la concessione degli spazi e dei servizi per la gestione dei [&hellip;]<\/p>\n                                <a title=\"Affidamento Corsi di Lingua Italiana\" class=\"read-more\" href=\"https:\/\/iicchicago.esteri.it\/it\/news\/dall_istituto\/2025\/03\/affidamento-corsi-di-lingua-italiana\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n            \n            <div class=\"col-md-12 mt-4 pb-4\">\n                <nav class=\"navigation col-md-12\" aria-label=\"Navigation\">\n                    <h2 class=\"screen-reader-text visually-hidden\">Paginazione<\/h2>\n                    <div class=\"nav-links\">\n                    <span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/pages\/18\/?pag=2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/pages\/18\/?pag=3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/pages\/18\/?pag=5\">5<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/pages\/18\/?pag=2\"><svg class=\"icon icon-primary\"><use xlink:href=\"https:\/\/iicchicago.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-chevron-right\"><\/use><\/svg>\n                                    <span class=\"visually-hidden\">Pagina successiva<\/span><\/a>                    <\/div>\n                <\/nav>\n            <\/div>   <!--.col-md-12 -->\n              <\/div><!--.row -->\n              \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":1,"href":"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":22,"href":"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/pages\/18\/revisions\/22"}],"wp:attachment":[{"href":"https:\/\/iicchicago.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}